{"id":1800,"date":"2020-01-16T15:26:02","date_gmt":"2020-01-16T15:26:02","guid":{"rendered":"https:\/\/odysseus.gocreations.info\/stay\/standard-double-or-twin-sea-view\/"},"modified":"2020-02-04T10:54:13","modified_gmt":"2020-02-04T10:54:13","slug":"standard-double-or-twin-sea-view","status":"publish","type":"stay","link":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/","title":{"rendered":"Standard Doppelzimmer Meerblick"},"content":{"rendered":"","protected":false},"featured_media":1370,"parent":0,"menu_order":33,"template":"","stay_type":[9],"class_list":["post-1800","stay","type-stay","status-publish","has-post-thumbnail","hentry","stay_type-rooms"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Standard Doppelzimmer Meerblick | Odysseus Hotel Paleokastritsa<\/title>\n<meta name=\"description\" content=\"Set on a hillside above one of the six beautiful bays of Paleokastritsa, this family-run hotel offers spectacular views of the Ionian Sea.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Standard Doppelzimmer Meerblick | Odysseus Hotel Paleokastritsa\" \/>\n<meta property=\"og:description\" content=\"Set on a hillside above one of the six beautiful bays of Paleokastritsa, this family-run hotel offers spectacular views of the Ionian Sea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/\" \/>\n<meta property=\"og:site_name\" content=\"Odysseus Hotel Paleokastritsa\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-04T10:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/\",\"url\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/\",\"name\":\"Standard Doppelzimmer Meerblick | Odysseus Hotel Paleokastritsa\",\"isPartOf\":{\"@id\":\"https:\/\/odysseushotel.gr\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg\",\"datePublished\":\"2020-01-16T15:26:02+00:00\",\"dateModified\":\"2020-02-04T10:54:13+00:00\",\"description\":\"Set on a hillside above one of the six beautiful bays of Paleokastritsa, this family-run hotel offers spectacular views of the Ionian Sea.\",\"breadcrumb\":{\"@id\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#primaryimage\",\"url\":\"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg\",\"contentUrl\":\"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/odysseushotel.gr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Standard Doppelzimmer Meerblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/odysseushotel.gr\/de\/#website\",\"url\":\"https:\/\/odysseushotel.gr\/de\/\",\"name\":\"Odysseus Hotel Paleokastritsa\",\"description\":\"Sea View Hotel Corfu\",\"publisher\":{\"@id\":\"https:\/\/odysseushotel.gr\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/odysseushotel.gr\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/odysseushotel.gr\/de\/#organization\",\"name\":\"Odysseus Hotel\",\"url\":\"https:\/\/odysseushotel.gr\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/odysseushotel.gr\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel.png\",\"contentUrl\":\"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel.png\",\"width\":249,\"height\":181,\"caption\":\"Odysseus Hotel\"},\"image\":{\"@id\":\"https:\/\/odysseushotel.gr\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Standard Doppelzimmer Meerblick | Odysseus Hotel Paleokastritsa","description":"Set on a hillside above one of the six beautiful bays of Paleokastritsa, this family-run hotel offers spectacular views of the Ionian Sea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/","og_locale":"de_DE","og_type":"article","og_title":"Standard Doppelzimmer Meerblick | Odysseus Hotel Paleokastritsa","og_description":"Set on a hillside above one of the six beautiful bays of Paleokastritsa, this family-run hotel offers spectacular views of the Ionian Sea.","og_url":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/","og_site_name":"Odysseus Hotel Paleokastritsa","article_modified_time":"2020-02-04T10:54:13+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/www.odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/","url":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/","name":"Standard Doppelzimmer Meerblick | Odysseus Hotel Paleokastritsa","isPartOf":{"@id":"https:\/\/odysseushotel.gr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#primaryimage"},"image":{"@id":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#primaryimage"},"thumbnailUrl":"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg","datePublished":"2020-01-16T15:26:02+00:00","dateModified":"2020-02-04T10:54:13+00:00","description":"Set on a hillside above one of the six beautiful bays of Paleokastritsa, this family-run hotel offers spectacular views of the Ionian Sea.","breadcrumb":{"@id":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#primaryimage","url":"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg","contentUrl":"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel-Standard-Double-or-Twin-Sea-View-6.jpg","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/odysseushotel.gr\/de\/stay\/standard-double-or-twin-sea-view\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/odysseushotel.gr\/de\/"},{"@type":"ListItem","position":2,"name":"Standard Doppelzimmer Meerblick"}]},{"@type":"WebSite","@id":"https:\/\/odysseushotel.gr\/de\/#website","url":"https:\/\/odysseushotel.gr\/de\/","name":"Odysseus Hotel Paleokastritsa","description":"Sea View Hotel Corfu","publisher":{"@id":"https:\/\/odysseushotel.gr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/odysseushotel.gr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/odysseushotel.gr\/de\/#organization","name":"Odysseus Hotel","url":"https:\/\/odysseushotel.gr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/odysseushotel.gr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel.png","contentUrl":"https:\/\/odysseushotel.gr\/wp-content\/uploads\/2020\/01\/Odysseus-Hotel.png","width":249,"height":181,"caption":"Odysseus Hotel"},"image":{"@id":"https:\/\/odysseushotel.gr\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/odysseushotel.gr\/de\/wp-json\/wp\/v2\/stay\/1800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/odysseushotel.gr\/de\/wp-json\/wp\/v2\/stay"}],"about":[{"href":"https:\/\/odysseushotel.gr\/de\/wp-json\/wp\/v2\/types\/stay"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/odysseushotel.gr\/de\/wp-json\/wp\/v2\/media\/1370"}],"wp:attachment":[{"href":"https:\/\/odysseushotel.gr\/de\/wp-json\/wp\/v2\/media?parent=1800"}],"wp:term":[{"taxonomy":"stay_type","embeddable":true,"href":"https:\/\/odysseushotel.gr\/de\/wp-json\/wp\/v2\/stay_type?post=1800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}